{"id":7278,"date":"2024-04-05T17:42:50","date_gmt":"2024-04-05T15:42:50","guid":{"rendered":"https:\/\/studioparasiliti.com\/?p=7278"},"modified":"2024-04-10T11:09:58","modified_gmt":"2024-04-10T09:09:58","slug":"diritto-oblio-e-web","status":"publish","type":"post","link":"https:\/\/studioparasiliti.com\/it\/diritto-oblio-e-web\/","title":{"rendered":"Diritto all\u2019oblio e web"},"content":{"rendered":"<p>A cura dell&#8217;Avv Chiara Parasiliti<\/p>\n<h4><span style=\"color: #1f497d;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-7319\" src=\"https:\/\/studioparasiliti.com\/wp-content\/uploads\/37cd93a0-5360-4217-9046-788550acde58-300x300.jpeg\" alt=\"l concetto di diritto oblio nel contesto del web, con elementi visivi che simboleggiano la privacy e la rimozione di informazioni personali\" width=\"500\" height=\"500\" srcset=\"https:\/\/studioparasiliti.com\/wp-content\/uploads\/37cd93a0-5360-4217-9046-788550acde58-300x300.jpeg 300w, https:\/\/studioparasiliti.com\/wp-content\/uploads\/37cd93a0-5360-4217-9046-788550acde58-150x150.jpeg 150w, https:\/\/studioparasiliti.com\/wp-content\/uploads\/37cd93a0-5360-4217-9046-788550acde58-768x768.jpeg 768w, https:\/\/studioparasiliti.com\/wp-content\/uploads\/37cd93a0-5360-4217-9046-788550acde58-650x650.jpeg 650w, https:\/\/studioparasiliti.com\/wp-content\/uploads\/37cd93a0-5360-4217-9046-788550acde58.jpeg 1024w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/span><\/h4>\n<p style=\"text-align: center;\"><span style=\"color: #999999;\">Immagine generata con IA\u00a0 su prompt personale<\/span><\/p>\n<h4><span style=\"color: #1f497d;\">Definizione del Diritto all&#8217;Oblio<\/span><\/h4>\n<p>Il diritto \u201call\u2019oblio\u201d \u00e8 il diritto che consente agli individui di richiedere, senza ingiustificato ritardo, la cancellazione dei propri dati personali quando ricorrano determinati motivi.<\/p>\n<ol>\n<li><strong>Non pi\u00f9 necessario:<\/strong> I dati personali <strong>non sono pi\u00f9 necessari rispetto alle finalit\u00e0<\/strong> per le quali sono stati raccolti o altrimenti trattati.<\/li>\n<\/ol>\n<p>Una volta che il motivo per il quale i dati sono stati raccolti viene meno, i dati devono essere cancellati.<\/p>\n<p>In questo caso il Titolare dovrebbe agire autonomamente alla cancellazione, non essendo una richiesta esplicita da parte dell\u2019interessato poich\u00e9 in mancanza starebbe effettuando un trattamento illecito dei dati.<\/p>\n<ol start=\"2\">\n<li><strong>Revoca del consenso<\/strong>: L\u2019interessato <strong>revoca il consenso<\/strong> su cui si basava il trattamento e non sussiste un altro fondamento giuridico per il trattamento.<\/li>\n<\/ol>\n<p>Questo diritto si innesta, quindi, nel contesto pi\u00f9 ampio del consenso al trattamento dei dati personali.<\/p>\n<p>L&#8217;assenza di un consenso esplicito, infatti, impone la cancellazione dei dati relativi all&#8217;interessato.<\/p>\n<p>Ma \u00e8 importante sottolineare come ogni persona ha il diritto di chiedere la cancellazione dei propri dati anche se ha revocato il consenso precedentemente accordato.<\/p>\n<ol start=\"3\">\n<li><strong>Opposizione al trattamento<\/strong>: L\u2019interessato <strong>si oppone<\/strong> al trattamento e non sussiste alcun motivo legittimo prevalente per procedere al trattamento.<\/li>\n<\/ol>\n<p>Il diritto all\u2019opposizione \u00e8 esercitabile specialmente contro il trattamento dei dati per finalit\u00e0 di marketing diretto, incluso la profilazione, o quando il trattamento si basa su interessi legittimi.<\/p>\n<ol start=\"4\">\n<li><strong>Trattamento illecito<\/strong>: I dati personali sono stati trattati illecitamente.<\/li>\n<\/ol>\n<p>In caso di trattamento illecito dei dati, questi devono essere eliminati, e in caso di mancato adempimento, sono previste sanzioni da parte dell\u2019autorit\u00e0 garante.<\/p>\n<ol start=\"5\">\n<li><strong>Obblighi legali<\/strong>: I dati personali devono essere cancellati per <strong>adempiere a un obbligo legale<\/strong> nell\u2019Unione Europea o negli Stati membri.<\/li>\n<li><strong>Consenso dei minor<\/strong>i: I dati personali sono stati <strong>raccolti in relazione all\u2019offerta di servizi della societ\u00e0 dell\u2019informazione a minori di 16 anni.<\/strong><\/li>\n<\/ol>\n<p>Occorre ricordare che il GDPR tutela unicamente le persone fisiche, di conseguenza, il diritto all\u2019oblio non potr\u00e0 essere invocato aziende per rimuovere informazioni che le riguardano.<\/p>\n<h4><span style=\"color: #1f497d;\">Il bilanciamento tra informazione e privacy<\/span><\/h4>\n<p>Il diritto all\u2019oblio <strong>non \u00e8 assoluto.<\/strong><\/p>\n<p>Esso deve essere bilanciato con altri diritti quali:<\/p>\n<ul>\n<li>diritto alla libert\u00e0 di espressione e di informazione;<\/li>\n<li>l&#8217;adempimento di un obbligo giuridico per l&#8217;adempimento di un obbligo o l&#8217;esecuzione di un compito di pubblico interesse oppure nell&#8217;esercizio di pubblici poteri di cui \u00e8 investito il titolare del trattamento;<\/li>\n<\/ul>\n<ul>\n<li>interesse pubblico in campo sanitario;<\/li>\n<li>ricerca storica, scientifica o statistica;<\/li>\n<li>\u00a0per l&#8217;accertamento, l&#8217;esercizio o la difesa di un diritto in sede giudiziaria.<\/li>\n<\/ul>\n<h4><span style=\"color: #1f497d;\">Responsabilit\u00e0 del Titolare del Trattamento<\/span><\/h4>\n<p>Il Considerando 59 del GDPR stabilisce che il titolare deve prevedere modalit\u00e0 volte ad <strong>agevolare l\u2019esercizio dei diritti <\/strong>da parte dell\u2019interessato potendo operare una valutazione circa la sussistenza del diritto.<\/p>\n<p>Al termine della valutazione il Titolare del trattamento, se il diritto alla cancellazione <strong>non \u00e8 applicabile<\/strong>, deve <strong>notiziare <\/strong>l\u2019interessato<strong> motivando <\/strong>il rifiuto alla cancellazione.<strong>\u00a0 <\/strong><\/p>\n<p>Se, invece, il diritto alla cancellazione \u00e8 applicabile, il Titolare del trattamento deve:<\/p>\n<ul>\n<li><strong>rimuovere \u201csenza ingiustificato ritardo\u201d <\/strong>le informazioni<strong>;<\/strong><\/li>\n<li>comunicare la cancellazione <strong>a ciascuno dei destinatari cui sono stati trasmessi i dati<\/strong>;<\/li>\n<li>in caso di dati \u201c<strong>resi pubblici<\/strong>\u201d (ad esempio perch\u00e9 pubblicati su un sito web) <strong>informare della richiesta <\/strong>di cancellazione<strong> altri titolari che trattano i dati personali cancellati, compresi \u201cqualsiasi link, copia o riproduzione<\/strong>\u201d<\/li>\n<\/ul>\n<h4><span style=\"color: #1f497d;\">Diritto all\u2019oblio e web<\/span><\/h4>\n<p>Il diritto all\u2019oblio nel mondo digitale, caratterizzato dalla \u201c<strong>condivisione<\/strong>\u201d (sharing) dei contenuti, \u00e8 strettamente collegato non solo alla cancellazione delle informazioni da parte del Titolare ma, anche, all\u2019<strong>eliminazione delle successive ripubblicazioni da parte di terzi soggetti.<\/strong><\/p>\n<p>Anche la Riforma Cartabia ha affrontato la questione con l\u2019art. 64-ter disp. att. c.p.p. \u201c<strong>il diritto all&#8217;oblio per imputati e indagati\u201d <\/strong>che cos\u00ec dispone \u00ab<em> La persona nei cui confronti sono stati pronunciati una sentenza di proscioglimento o di non luogo a procedere ovvero un provvedimento di archiviazione pu\u00f2 richiedere che sia preclusa l\u2019indicizzazione o che sia disposta la deindicizzazione, sulla rete internet, dei dati personali riportati nella sentenza o nel provvedimento, ai sensi e nei limiti dell\u2019articolo 17 del Regolamento (UE) 2016\/679 del Parlamento europeo e del Consiglio, del 27 aprile 2016. Resta fermo quanto previsto dall\u2019articolo 52 del decreto legislativo 30 giugno 2003, n. 196 [\u2026]<\/em>\u00bb.<\/p>\n<p>Ci\u00f2 significa che una persona assolta o contro la quale \u00e8 stata emessa una decisione di non perseguibilit\u00e0 o un ordine di archiviazione pu\u00f2 richiedere la deindicizzazione dei propri dati personali da Internet.<\/p>\n<p>In questo contesto, il diritto degli interessati ad ottenere <strong>deindicizzate dalla ricerca<\/strong> delle proprie informazioni personali, creando in linea teorica, una impossibilit\u00e0 di trovarle sul Web, fu consacrato la sentenza Costeja della Corte di Giustizia dell\u2019Unione Europea.<\/p>\n<p>Ma per comprendere la portata del problema occorre precisare che<strong> l\u2019informazione non viene eliminata, essa continuer\u00e0 ad essere presente in rete.<\/strong><\/p>\n<p>Le linee guida 05\/2019 dell\u2019European Data Protection Board (EDPB) sui criteri per l\u2019esercizio del diritto all\u2019oblio nel caso dei motori di ricerca spiegano, infatti, che \u00ab<em>Se un interessato ottiene la deindicizzazione di un particolare contenuto, ci\u00f2 determina la cancellazione di tale contenuto specifico dall\u2019elenco dei risultati di ricerca relativi all\u2019interessato, quando la ricerca \u00e8, in via generale, effettuata a partire dal suo nome. Il contenuto rester\u00e0 tuttavia disponibile se vengono utilizzati altri criteri di ricerca [\u2026] Ad esempio, un interessato pu\u00f2 richiedere la rimozione dall\u2019indice di un motore di ricerca di dati personali provenienti da un mezzo di comunicazione, quale un articolo di giornale. In questo caso, il link ai dati personali pu\u00f2 essere rimosso dall\u2019indice del motore di ricerca, ma l\u2019articolo in questione rester\u00e0 comunque sotto il controllo del mezzo di comunicazione e <strong>pu\u00f2 rimanere pubblicamente disponibile e accessibile, sebbene non sia pi\u00f9 visibile nei risultati di ricerca basati sulle interrogazioni che includono, in linea di principio, il nome dell\u2019interessato<\/strong><\/em>.\u00bb<\/p>\n<p>Il problema della identificabilit\u00e0 \u00e8 stato affrontato, da ultimo, dalla Corte di Giustizia dell&#8217;Unione Europea, con la sentenza del 7\/3\/2024, nella causa C-479\/22, che ha evidenziato come, con ricerche incrociate su Internet, sia facile abbinare informazioni, in partenza non nominative, alla persona cui si riferiscono.<\/p>\n<p>La persona \u00e8 identificabile, secondo la Corte UE, anche quando si possa arrivare all\u2019identit\u00e0, a partire da informazioni non nominative, utilizzando l\u2019insieme dei fattori oggettivi, tra cui i costi e il tempo necessari per l\u2019identificazione, tenendo conto <strong>sia delle tecnologie disponibili al momento del trattamento sia degli sviluppi tecnologici.<\/strong><\/p>\n<p>La sentenza della Corte di Giustizia dell&#8217;Unione Europea del 7\/3\/2024 sull&#8217;identificabilit\u00e0 delle persone su Internet rafforza l&#8217;importanza della protezione dei dati personali e la necessit\u00e0 di utilizzare tecniche come l&#8217;anonimizzazione e la pseudonimizzazione per proteggere la privacy degli individui.<\/p>\n<p>&nbsp;<\/p>\n<h6><a href=\"https:\/\/studioparasiliti.com\/it\/disclaimer\/\"><span style=\"color: #1f497d;\">Disclaimer<\/span><\/a><\/h6>\n<h6><\/h6>\n<p style=\"text-align: center;\">\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;identificabilit\u00e0 delle persone su Internet rafforza l&#8217;importanza della protezione dei dati personali.<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[133,132],"tags":[],"class_list":["post-7278","post","type-post","status-publish","format-standard","hentry","category-diritto-digitale","category-gdpr-compliance"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Diritto all\u2019oblio e web | Studio Legale Parasiliti<\/title>\n<meta name=\"description\" content=\"L&#039;identificabilit\u00e0 delle persone su Internet rafforza l&#039;importanza della protezione dei dati personali.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/studioparasiliti.com\/it\/diritto-oblio-e-web\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Diritto all\u2019oblio e web | Studio Legale Parasiliti\" \/>\n<meta property=\"og:description\" content=\"L&#039;identificabilit\u00e0 delle persone su Internet rafforza l&#039;importanza della protezione dei dati personali.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/studioparasiliti.com\/it\/diritto-oblio-e-web\/\" \/>\n<meta property=\"og:site_name\" content=\"Studio Legale Parasiliti\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-05T15:42:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-10T09:09:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/studioparasiliti.com\/wp-content\/uploads\/37cd93a0-5360-4217-9046-788550acde58-300x300.jpeg\" \/>\n<meta name=\"author\" content=\"Studio Parasiliti\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Studio Parasiliti\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/studioparasiliti.com\\\/it\\\/diritto-oblio-e-web\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/studioparasiliti.com\\\/it\\\/diritto-oblio-e-web\\\/\"},\"author\":{\"name\":\"Studio Parasiliti\",\"@id\":\"https:\\\/\\\/studioparasiliti.com\\\/it\\\/#\\\/schema\\\/person\\\/0427e99804b64009538f173d93bdd1ed\"},\"headline\":\"Diritto all\u2019oblio e web\",\"datePublished\":\"2024-04-05T15:42:50+00:00\",\"dateModified\":\"2024-04-10T09:09:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/studioparasiliti.com\\\/it\\\/diritto-oblio-e-web\\\/\"},\"wordCount\":1106,\"publisher\":{\"@id\":\"https:\\\/\\\/studioparasiliti.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/studioparasiliti.com\\\/it\\\/diritto-oblio-e-web\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/studioparasiliti.com\\\/wp-content\\\/uploads\\\/37cd93a0-5360-4217-9046-788550acde58-300x300.jpeg\",\"articleSection\":[\"Diritto Digitale\",\"GDPR Compliance\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/studioparasiliti.com\\\/it\\\/diritto-oblio-e-web\\\/\",\"url\":\"https:\\\/\\\/studioparasiliti.com\\\/it\\\/diritto-oblio-e-web\\\/\",\"name\":\"Diritto all\u2019oblio e web | Studio Legale Parasiliti\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/studioparasiliti.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/studioparasiliti.com\\\/it\\\/diritto-oblio-e-web\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/studioparasiliti.com\\\/it\\\/diritto-oblio-e-web\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/studioparasiliti.com\\\/wp-content\\\/uploads\\\/37cd93a0-5360-4217-9046-788550acde58-300x300.jpeg\",\"datePublished\":\"2024-04-05T15:42:50+00:00\",\"dateModified\":\"2024-04-10T09:09:58+00:00\",\"description\":\"L'identificabilit\u00e0 delle persone su Internet rafforza l'importanza della protezione dei dati personali.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/studioparasiliti.com\\\/it\\\/diritto-oblio-e-web\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/studioparasiliti.com\\\/it\\\/diritto-oblio-e-web\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/studioparasiliti.com\\\/it\\\/diritto-oblio-e-web\\\/#primaryimage\",\"url\":\"https:\\\/\\\/studioparasiliti.com\\\/wp-content\\\/uploads\\\/37cd93a0-5360-4217-9046-788550acde58-300x300.jpeg\",\"contentUrl\":\"https:\\\/\\\/studioparasiliti.com\\\/wp-content\\\/uploads\\\/37cd93a0-5360-4217-9046-788550acde58-300x300.jpeg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/studioparasiliti.com\\\/it\\\/diritto-oblio-e-web\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/studioparasiliti.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Diritto all\u2019oblio e web\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/studioparasiliti.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/studioparasiliti.com\\\/it\\\/\",\"name\":\"Studio Legale Parasiliti\",\"description\":\"Passione per il Diritto\",\"publisher\":{\"@id\":\"https:\\\/\\\/studioparasiliti.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/studioparasiliti.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/studioparasiliti.com\\\/it\\\/#organization\",\"name\":\"Studio Legale Carlo Parasiliti\",\"url\":\"https:\\\/\\\/studioparasiliti.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/studioparasiliti.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Studio Legale Carlo Parasiliti\"},\"image\":{\"@id\":\"https:\\\/\\\/studioparasiliti.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/studioparasiliti.com\\\/it\\\/#\\\/schema\\\/person\\\/0427e99804b64009538f173d93bdd1ed\",\"name\":\"Studio Parasiliti\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Diritto all\u2019oblio e web | Studio Legale Parasiliti","description":"L'identificabilit\u00e0 delle persone su Internet rafforza l'importanza della protezione dei dati personali.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/studioparasiliti.com\/it\/diritto-oblio-e-web\/","og_locale":"it_IT","og_type":"article","og_title":"Diritto all\u2019oblio e web | Studio Legale Parasiliti","og_description":"L'identificabilit\u00e0 delle persone su Internet rafforza l'importanza della protezione dei dati personali.","og_url":"https:\/\/studioparasiliti.com\/it\/diritto-oblio-e-web\/","og_site_name":"Studio Legale Parasiliti","article_published_time":"2024-04-05T15:42:50+00:00","article_modified_time":"2024-04-10T09:09:58+00:00","og_image":[{"url":"https:\/\/studioparasiliti.com\/wp-content\/uploads\/37cd93a0-5360-4217-9046-788550acde58-300x300.jpeg","type":"","width":"","height":""}],"author":"Studio Parasiliti","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Studio Parasiliti","Tempo di lettura stimato":"6 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/studioparasiliti.com\/it\/diritto-oblio-e-web\/#article","isPartOf":{"@id":"https:\/\/studioparasiliti.com\/it\/diritto-oblio-e-web\/"},"author":{"name":"Studio Parasiliti","@id":"https:\/\/studioparasiliti.com\/it\/#\/schema\/person\/0427e99804b64009538f173d93bdd1ed"},"headline":"Diritto all\u2019oblio e web","datePublished":"2024-04-05T15:42:50+00:00","dateModified":"2024-04-10T09:09:58+00:00","mainEntityOfPage":{"@id":"https:\/\/studioparasiliti.com\/it\/diritto-oblio-e-web\/"},"wordCount":1106,"publisher":{"@id":"https:\/\/studioparasiliti.com\/it\/#organization"},"image":{"@id":"https:\/\/studioparasiliti.com\/it\/diritto-oblio-e-web\/#primaryimage"},"thumbnailUrl":"https:\/\/studioparasiliti.com\/wp-content\/uploads\/37cd93a0-5360-4217-9046-788550acde58-300x300.jpeg","articleSection":["Diritto Digitale","GDPR Compliance"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/studioparasiliti.com\/it\/diritto-oblio-e-web\/","url":"https:\/\/studioparasiliti.com\/it\/diritto-oblio-e-web\/","name":"Diritto all\u2019oblio e web | Studio Legale Parasiliti","isPartOf":{"@id":"https:\/\/studioparasiliti.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/studioparasiliti.com\/it\/diritto-oblio-e-web\/#primaryimage"},"image":{"@id":"https:\/\/studioparasiliti.com\/it\/diritto-oblio-e-web\/#primaryimage"},"thumbnailUrl":"https:\/\/studioparasiliti.com\/wp-content\/uploads\/37cd93a0-5360-4217-9046-788550acde58-300x300.jpeg","datePublished":"2024-04-05T15:42:50+00:00","dateModified":"2024-04-10T09:09:58+00:00","description":"L'identificabilit\u00e0 delle persone su Internet rafforza l'importanza della protezione dei dati personali.","breadcrumb":{"@id":"https:\/\/studioparasiliti.com\/it\/diritto-oblio-e-web\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/studioparasiliti.com\/it\/diritto-oblio-e-web\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/studioparasiliti.com\/it\/diritto-oblio-e-web\/#primaryimage","url":"https:\/\/studioparasiliti.com\/wp-content\/uploads\/37cd93a0-5360-4217-9046-788550acde58-300x300.jpeg","contentUrl":"https:\/\/studioparasiliti.com\/wp-content\/uploads\/37cd93a0-5360-4217-9046-788550acde58-300x300.jpeg"},{"@type":"BreadcrumbList","@id":"https:\/\/studioparasiliti.com\/it\/diritto-oblio-e-web\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/studioparasiliti.com\/it\/"},{"@type":"ListItem","position":2,"name":"Diritto all\u2019oblio e web"}]},{"@type":"WebSite","@id":"https:\/\/studioparasiliti.com\/it\/#website","url":"https:\/\/studioparasiliti.com\/it\/","name":"Studio Legale Parasiliti","description":"Passione per il Diritto","publisher":{"@id":"https:\/\/studioparasiliti.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/studioparasiliti.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/studioparasiliti.com\/it\/#organization","name":"Studio Legale Carlo Parasiliti","url":"https:\/\/studioparasiliti.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/studioparasiliti.com\/it\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Studio Legale Carlo Parasiliti"},"image":{"@id":"https:\/\/studioparasiliti.com\/it\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/studioparasiliti.com\/it\/#\/schema\/person\/0427e99804b64009538f173d93bdd1ed","name":"Studio Parasiliti"}]}},"_links":{"self":[{"href":"https:\/\/studioparasiliti.com\/it\/wp-json\/wp\/v2\/posts\/7278","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/studioparasiliti.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/studioparasiliti.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/studioparasiliti.com\/it\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/studioparasiliti.com\/it\/wp-json\/wp\/v2\/comments?post=7278"}],"version-history":[{"count":2,"href":"https:\/\/studioparasiliti.com\/it\/wp-json\/wp\/v2\/posts\/7278\/revisions"}],"predecessor-version":[{"id":7338,"href":"https:\/\/studioparasiliti.com\/it\/wp-json\/wp\/v2\/posts\/7278\/revisions\/7338"}],"wp:attachment":[{"href":"https:\/\/studioparasiliti.com\/it\/wp-json\/wp\/v2\/media?parent=7278"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/studioparasiliti.com\/it\/wp-json\/wp\/v2\/categories?post=7278"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/studioparasiliti.com\/it\/wp-json\/wp\/v2\/tags?post=7278"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}